{"id":4868,"date":"2023-09-07T15:59:56","date_gmt":"2023-09-07T19:59:56","guid":{"rendered":"https:\/\/fosfeminista.org\/news-and-stories\/abortion-mexico\/"},"modified":"2025-09-19T18:07:51","modified_gmt":"2025-09-19T22:07:51","slug":"abortion-mexico","status":"publish","type":"article","link":"https:\/\/fosfeminista.org\/pt\/news-and-stories\/abortion-mexico\/","title":{"rendered":"Vit\u00f3ria hist\u00f3rica do Green Wave no M\u00e9xico"},"template":"","class_list":["post-4868","article","type-article","status-publish","has-post-thumbnail","hentry","article_format-statements","issue_tax-legal-abortion","issue_legacy-abortion","location-mexico"],"acf":{"details":{"":null,"article_type":false,"article_format":44,"authors":"","add_button":false,"button_type":"link","button":"","download":"","download_button_text":"","featured_image":3454},"sidebar":{"issues":{"title":"Quest\u00f5es priorit\u00e1rias","issues":[34]},"locations":{"title":"Localiza\u00e7\u00e3o","locations":[102]},"partners":{"title":"Parceiros","partners":""}},"page_layout":[{"acf_fc_layout":"layout_hero_article","_acfe_flexible_toggle":null,"component_hero_article":{"":null,"anchor_id":""}},{"acf_fc_layout":"layout_wysiwyg","_acfe_flexible_toggle":null,"component_wysiwyg":{"content":"<p style=\"font-weight: 400;\"><strong>NOVA YORK, NY <\/strong>- Na quarta-feira, 6 de setembro, a Suprema Corte do M\u00e9xico <a href=\"https:\/\/gire.org.mx\/blog\/corte-despenaliza-el-aborto-a-nivel-federal\/\">decidiu descriminalizar o aborto em n\u00edvel federal<\/a>. Ap\u00f3s o <a href=\"https:\/\/fosfeminista.orgmedia\/raising-the-green-wave-in-mexico\/\">Decis\u00e3o da Corte em setembro de 2021<\/a> A decis\u00e3o do Supremo Tribunal Federal (STF), que afirmou que as penalidades criminais para o aborto eram inconstitucionais porque violavam a dignidade humana, a autonomia, a igualdade, a sa\u00fade reprodutiva e a liberdade, entre outros direitos, conclui agora que a se\u00e7\u00e3o do c\u00f3digo penal federal que criminaliza o aborto n\u00e3o estar\u00e1 mais em vigor e, portanto, nenhuma mulher ou pessoa gr\u00e1vida pode ser punida por fazer um aborto.<\/p>\n<p style=\"font-weight: 400;\">Apesar da decis\u00e3o de 2021, muitos c\u00f3digos penais em n\u00edvel estadual mantiveram o aborto como crime, com algumas exce\u00e7\u00f5es. Apenas 12 dos 32 estados mexicanos legalizaram oficialmente o aborto, incluindo <a href=\"https:\/\/gire.org.mx\/blog\/la-corte-despenaliza-el-aborto-en-aguascalientes\/\">Estado de Aguascalientes na semana passada.<\/a><\/p>\n<p style=\"font-weight: 400;\">Essa nova decis\u00e3o garante que as pessoas possam procurar e oferecer atendimento ao aborto em institui\u00e7\u00f5es de sa\u00fade federais em qualquer estado mexicano sem serem perseguidas pelos tribunais. A Suprema Corte tamb\u00e9m pediu a todos os ju\u00edzes em n\u00edvel federal e local que tomem decis\u00f5es com base nessas decis\u00f5es federais relacionadas ao aborto. Embora o aborto ainda n\u00e3o seja totalmente legal at\u00e9 que todos os 32 estados o eliminem de seus c\u00f3digos penais, agora nenhuma pessoa pode ser processada pelo sistema judicial.<\/p>\n<p style=\"font-weight: 400;\">Essa decis\u00e3o hist\u00f3rica ocorre ap\u00f3s anos de lit\u00edgio estrat\u00e9gico com a Suprema Corte Mexicana, liderado pela parceira da F\u00f2s Feminista, <a href=\"https:\/\/gire.org.mx\/\">GIRE<\/a>, e outras organiza\u00e7\u00f5es feministas.<\/p>\n<p style=\"font-weight: 400;\">Em resposta \u00e0 decis\u00e3o, <strong>Giselle Carino, diretora executiva da <\/strong><strong>F\u00f2s Feminista<\/strong><strong>,<\/strong> uma alian\u00e7a feminista internacional que ap\u00f3ia os esfor\u00e7os do GIRE, emitiu a seguinte declara\u00e7\u00e3o:<\/p>\n\n<blockquote>\n<p style=\"font-weight: 400;\">\u201cCelebramos a decis\u00e3o da Corte como uma vit\u00f3ria significativa para todas as mulheres, meninas e pessoas que podem engravidar no M\u00e9xico e, particularmente, para as pessoas marginalizadas que s\u00e3o mais afetadas pela criminaliza\u00e7\u00e3o do aborto. Tamb\u00e9m parabenizamos o GIRE e outras organiza\u00e7\u00f5es feministas por seu trabalho cr\u00edtico que ajudou a tornar esse progresso uma realidade. Apesar do terr\u00edvel retrocesso do acesso nos Estados Unidos, est\u00e1 claro que o mundo est\u00e1 abrindo o acesso ao aborto, sendo o M\u00e9xico agora o exemplo mais recente. A Onda Verde de feministas que lutam em solidariedade pela justi\u00e7a do aborto est\u00e1 mais forte do que nunca.\u201d<\/p>\n<\/blockquote>\n<p style=\"font-weight: 400;\">Rebecca Ramos, diretora da <a href=\"https:\/\/gire.org.mx\/\">GIRE<\/a>, que entrou com a a\u00e7\u00e3o judicial que motivou a decis\u00e3o da Corte na quarta-feira, expressou:<\/p>\n\n<blockquote>\n<p style=\"font-weight: 400;\">\u201cEssa decis\u00e3o \u00e9 um marco hist\u00f3rico que representa um ponto de inflex\u00e3o na defesa da justi\u00e7a reprodutiva. As institui\u00e7\u00f5es federais de sa\u00fade ser\u00e3o obrigadas a fornecer servi\u00e7os de aborto quando solicitados, o que significa que mais de 70% das mulheres e pessoas com capacidade de engravidar podem agora ter acesso a um aborto legal no M\u00e9xico. Ainda assim, h\u00e1 trabalho a ser feito. Esperamos que os estados que ainda n\u00e3o atualizaram suas leis locais sigam o exemplo da mais alta corte de nossa na\u00e7\u00e3o e ajam imediatamente para garantir a autonomia do corpo.\u201d<\/p>\n<\/blockquote>\n<p style=\"font-weight: 400;\">A decis\u00e3o do M\u00e9xico de descriminalizar o aborto faz parte do aumento da <a href=\"https:\/\/fosfeminista.orgmedia\/a-brief-history-of-the-green-wave\/\">Onda verde para os direitos reprodutivos<\/a> que est\u00e1 varrendo a Am\u00e9rica Latina e o Caribe. A Onda Verde surgiu na Argentina quando diversos grupos da sociedade civil se uniram em torno da demanda pela descriminaliza\u00e7\u00e3o do aborto, culminando com a aprova\u00e7\u00e3o de uma legisla\u00e7\u00e3o em dezembro de 2020 que permitiu que as pessoas interrompessem suas gesta\u00e7\u00f5es durante o primeiro trimestre. Depois, em fevereiro de 2022, a Suprema Corte da Col\u00f4mbia votou pela descriminaliza\u00e7\u00e3o do aborto at\u00e9 24 semanas.<\/p>\n<p style=\"font-weight: 400;\">A ascens\u00e3o da Onda Verde contrasta fortemente com os acontecimentos nos Estados Unidos, onde a Suprema Corte reduziu o direito legal ao aborto e tentou proibir medicamentos que t\u00eam sido usados com seguran\u00e7a para controlar e interromper a gravidez.<\/p>\n<p style=\"font-weight: 400;\">###<\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/fosfeminista.orgabout-us\/\"><strong>F\u00f2s Feminista<\/strong><\/a> \u00e9 uma alian\u00e7a feminista internacional centrada na sa\u00fade sexual e reprodutiva, nos direitos e na justi\u00e7a para mulheres, meninas e pessoas com diversidade de g\u00eanero. Juntamente com mais de 135 organiza\u00e7\u00f5es locais em todo o mundo, n\u00f3s nos envolvemos em cuidados com a sa\u00fade, educa\u00e7\u00e3o e defesa de direitos para promover nossa agenda. Isso inclui a presta\u00e7\u00e3o de servi\u00e7os de sa\u00fade sexual e reprodutiva e a implementa\u00e7\u00e3o de estrat\u00e9gias baseadas na comunidade que tornam a sa\u00fade sexual e reprodutiva mais acess\u00edvel a mulheres, meninas e outras pessoas marginalizadas. Tamb\u00e9m envolvemos os jovens com educa\u00e7\u00e3o sexual abrangente e prestamos atendimento a sobreviventes de viol\u00eancia de g\u00eanero. Estamos ao lado de nossos parceiros nas ruas, nos tribunais e em outros espa\u00e7os de defesa como uma voz feminista sem remorso, resistindo \u00e0 injusti\u00e7a e defendendo a igualdade de g\u00eanero e os direitos reprodutivos local e globalmente.<\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/gire.org.mx\/?lang=en\"><strong>GIRE<\/strong><\/a> \u00e9 uma organiza\u00e7\u00e3o feminista de direitos humanos que trabalha h\u00e1 quase 30 anos acompanhando mulheres e outras pessoas com a capacidade de engravidar no exerc\u00edcio de seus direitos reprodutivos. Por meio de uma estrat\u00e9gia abrangente de defesa de pol\u00edticas p\u00fablicas e legislativas, acompanhamento de casos, pesquisas e comunica\u00e7\u00f5es, nosso objetivo \u00e9 levar adiante quest\u00f5es como aborto, viol\u00eancia obst\u00e9trica, mortalidade materna, equil\u00edbrio entre vida pessoal e profissional e acesso a t\u00e9cnicas de reprodu\u00e7\u00e3o assistida.<\/p>","":null,"anchor_id":""}}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Historic Win For the Green Wave in Mexico - F\u00f2s Feminista<\/title>\n<meta name=\"description\" content=\"F\u00f2s Feminista Applauds Mexican Court Ruling to Decriminalize Abortion at the Federal Level, Another Victory of the Rising Green Wave.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fosfeminista.org\/pt\/news-and-stories\/abortion-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historic Win For the Green Wave in Mexico - F\u00f2s Feminista\" \/>\n<meta property=\"og:description\" content=\"F\u00f2s Feminista Applauds Mexican Court Ruling to Decriminalize Abortion at the Federal Level, Another Victory of the Rising Green Wave.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fosfeminista.org\/pt\/news-and-stories\/abortion-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"F\u00f2s Feminista\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T22:07:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fosfeminista.org\/wp-content\/uploads\/2023\/09\/Mexico-CDD-Mexico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1964\" \/>\n\t<meta property=\"og:image:height\" content=\"1314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/abortion-mexico\\\/\",\"url\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/abortion-mexico\\\/\",\"name\":\"Historic Win For the Green Wave in Mexico - F\u00f2s Feminista\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/abortion-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/abortion-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fosfeminista.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Mexico-CDD-Mexico.jpg\",\"datePublished\":\"2023-09-07T19:59:56+00:00\",\"dateModified\":\"2025-09-19T22:07:51+00:00\",\"description\":\"F\u00f2s Feminista Applauds Mexican Court Ruling to Decriminalize Abortion at the Federal Level, Another Victory of the Rising Green Wave.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/abortion-mexico\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/abortion-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/abortion-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fosfeminista.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Mexico-CDD-Mexico.jpg\",\"contentUrl\":\"https:\\\/\\\/fosfeminista.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Mexico-CDD-Mexico.jpg\",\"width\":1964,\"height\":1314},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/abortion-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fosfeminista.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Historic Win For the Green Wave in Mexico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/#website\",\"url\":\"https:\\\/\\\/fosfeminista.org\\\/\",\"name\":\"F\u00f2s Feminista\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fosfeminista.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historic Win For the Green Wave in Mexico - F\u00f2s Feminista","description":"F\u00f2s Feminista Applauds Mexican Court Ruling to Decriminalize Abortion at the Federal Level, Another Victory of the Rising Green Wave.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fosfeminista.org\/pt\/news-and-stories\/abortion-mexico\/","og_locale":"pt_BR","og_type":"article","og_title":"Historic Win For the Green Wave in Mexico - F\u00f2s Feminista","og_description":"F\u00f2s Feminista Applauds Mexican Court Ruling to Decriminalize Abortion at the Federal Level, Another Victory of the Rising Green Wave.","og_url":"https:\/\/fosfeminista.org\/pt\/news-and-stories\/abortion-mexico\/","og_site_name":"F\u00f2s Feminista","article_modified_time":"2025-09-19T22:07:51+00:00","og_image":[{"width":1964,"height":1314,"url":"https:\/\/fosfeminista.org\/wp-content\/uploads\/2023\/09\/Mexico-CDD-Mexico.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fosfeminista.org\/news-and-stories\/abortion-mexico\/","url":"https:\/\/fosfeminista.org\/news-and-stories\/abortion-mexico\/","name":"Historic Win For the Green Wave in Mexico - F\u00f2s Feminista","isPartOf":{"@id":"https:\/\/fosfeminista.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fosfeminista.org\/news-and-stories\/abortion-mexico\/#primaryimage"},"image":{"@id":"https:\/\/fosfeminista.org\/news-and-stories\/abortion-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/fosfeminista.org\/wp-content\/uploads\/2023\/09\/Mexico-CDD-Mexico.jpg","datePublished":"2023-09-07T19:59:56+00:00","dateModified":"2025-09-19T22:07:51+00:00","description":"F\u00f2s Feminista Applauds Mexican Court Ruling to Decriminalize Abortion at the Federal Level, Another Victory of the Rising Green Wave.","breadcrumb":{"@id":"https:\/\/fosfeminista.org\/news-and-stories\/abortion-mexico\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fosfeminista.org\/news-and-stories\/abortion-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fosfeminista.org\/news-and-stories\/abortion-mexico\/#primaryimage","url":"https:\/\/fosfeminista.org\/wp-content\/uploads\/2023\/09\/Mexico-CDD-Mexico.jpg","contentUrl":"https:\/\/fosfeminista.org\/wp-content\/uploads\/2023\/09\/Mexico-CDD-Mexico.jpg","width":1964,"height":1314},{"@type":"BreadcrumbList","@id":"https:\/\/fosfeminista.org\/news-and-stories\/abortion-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fosfeminista.org\/"},{"@type":"ListItem","position":2,"name":"Historic Win For the Green Wave in Mexico"}]},{"@type":"WebSite","@id":"https:\/\/fosfeminista.org\/#website","url":"https:\/\/fosfeminista.org\/","name":"F\u00f2s Feminista","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fosfeminista.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/fosfeminista.org\/pt\/wp-json\/wp\/v2\/article\/4868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fosfeminista.org\/pt\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/fosfeminista.org\/pt\/wp-json\/wp\/v2\/types\/article"}],"version-history":[{"count":1,"href":"https:\/\/fosfeminista.org\/pt\/wp-json\/wp\/v2\/article\/4868\/revisions"}],"predecessor-version":[{"id":5090,"href":"https:\/\/fosfeminista.org\/pt\/wp-json\/wp\/v2\/article\/4868\/revisions\/5090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fosfeminista.org\/pt\/wp-json\/wp\/v2\/media\/3454"}],"wp:attachment":[{"href":"https:\/\/fosfeminista.org\/pt\/wp-json\/wp\/v2\/media?parent=4868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}