{"id":4854,"date":"2023-05-09T14:46:34","date_gmt":"2023-05-09T18:46:34","guid":{"rendered":"https:\/\/fosfeminista.org\/news-and-stories\/resolution-justiceforbeatriz\/"},"modified":"2025-09-19T18:07:52","modified_gmt":"2025-09-19T22:07:52","slug":"resolution-justiceforbeatriz","status":"publish","type":"article","link":"https:\/\/fosfeminista.org\/es\/news-and-stories\/resolution-justiceforbeatriz\/","title":{"rendered":"F\u00f2s Feminista celebra la resoluci\u00f3n de la C\u00e1mara de Representantes de EE. UU. en apoyo a #JusticeforBeatriz"},"template":"","class_list":["post-4854","article","type-article","status-publish","has-post-thumbnail","hentry","article_format-statements","issue_tax-legal-abortion","issue_legacy-abortion","location-united-states"],"acf":{"details":{"":null,"article_type":false,"article_format":44,"authors":"","add_button":false,"button_type":"link","button":"","download":"","download_button_text":"","featured_image":3484},"sidebar":{"issues":{"title":"Cuestiones prioritarias","issues":[34]},"locations":{"title":"Ubicaci\u00f3n","locations":[147]},"partners":{"title":"Socios","partners":""}},"page_layout":[{"acf_fc_layout":"layout_hero_article","_acfe_flexible_toggle":null,"component_hero_article":{"":null,"anchor_id":""}},{"acf_fc_layout":"layout_wysiwyg","_acfe_flexible_toggle":null,"component_wysiwyg":{"content":"<b>Washington, D.C. \u2014 <\/b><span style=\"font-weight: 400;\">\u00a0F\u00f2s Feminista aplaude a la representante estadounidense Nikema Williams (D-GA) <\/span><a href=\"https:\/\/www.congress.gov\/bill\/118th-congress\/house-concurrent-resolution\/39\/actions?s=1&amp;r=2&amp;q=%7B%22search%22%3A%5B%22%22%5D%7D\"><span style=\"font-weight: 400;\">presentaci\u00f3n de una resoluci\u00f3n de la C\u00e1mara de Diputados<\/span><\/a><span style=\"font-weight: 400;\"> que ofrece solidaridad a las feministas de El Salvador que est\u00e1n exigiendo responsabilidades a su gobierno a trav\u00e9s de la <\/span><a href=\"https:\/\/justiciaparabeatriz.org\/en\/\"><span style=\"font-weight: 400;\"># Justicia para Beatriz<\/span><\/a><span style=\"font-weight: 400;\"> movimiento. La resoluci\u00f3n tambi\u00e9n rechaza rotundamente la criminalizaci\u00f3n de la atenci\u00f3n al aborto en cualquier forma o modalidad, en El Salvador, en los Estados Unidos y en otros lugares. El caso de Beatriz, de El Salvador, fue <\/span><a href=\"https:\/\/www.reuters.com\/world\/americas\/human-rights-court-begins-review-high-stakes-el-salvador-abortion-case-2023-03-22\/\"><span style=\"font-weight: 400;\">argument\u00f3 ante la Corte Interamericana de Derechos Humanos a finales de marzo<\/span><\/a><span style=\"font-weight: 400;\">. La sentencia pendiente de la Corte tendr\u00e1 repercusiones duraderas no solo para El Salvador, sino para toda la regi\u00f3n, ya que es la primera vez que la Corte aborda un caso espec\u00edfico sobre el aborto.\u00a0\u00a0\u00a0<\/span>\n\n<span style=\"font-weight: 400;\">En apoyo al representante Williams.\u2019 <\/span><a href=\"https:\/\/www.congress.gov\/bill\/118th-congress\/house-concurrent-resolution\/39\/actions?s=1&amp;r=2&amp;q=%7B%22search%22%3A%5B%22%22%5D%7D\"><span style=\"font-weight: 400;\">resoluci\u00f3n<\/span><\/a><span style=\"font-weight: 400;\">, el movimiento global #JusticiaParaBeatriz y en oposici\u00f3n a los l\u00edderes que penalizan el aborto en El Salvador, en los Estados Unidos y en todo el mundo., <\/span><a href=\"https:\/\/twitter.com\/_kolivera\"><b>Katherine Olivera<\/b><\/a><b>, subdirector de pol\u00edtica global de EE. UU.<\/b><b> en F\u00f2s Feminista, emiti\u00f3 la siguiente declaraci\u00f3n:<\/b>\n<blockquote><span style=\"font-weight: 400;\">\u201cEl caso de Beatriz es desgarrador para las feministas de todo el mundo. Toda persona tiene derecho a tomar decisiones sobre su propio cuerpo y su salud, sin coacci\u00f3n ni interferencias. La negaci\u00f3n de estos derechos es una violaci\u00f3n de los derechos humanos fundamentales, simple y llanamente.<\/span>\n\n<span style=\"font-weight: 400;\">\u201cEn reconocimiento de la amenaza inminente que supone la criminalizaci\u00f3n, esta semana nuestros aliados en la C\u00e1mara de Representantes de los Estados Unidos alzaron la voz en defensa de los derechos que se le niegan a Beatriz. <\/span><span style=\"font-weight: 400;\">La representante Nikema Williams y sus valientes colegas de la C\u00e1mara de Diputados demostraron que la fuerza de nuestro movimiento trasciende las fronteras en momentos de crisis al alzar sus voces para exigir que la Corte Interamericana de Derechos Humanos haga justicia a Beatriz.\u00a0<\/span>\n\n<span style=\"font-weight: 400;\">\u201cLa amenaza de la criminalizaci\u00f3n no es descabellada ni inimaginable: est\u00e1 ocurriendo ante nuestros ojos. Es el destino al que los extremistas antiaborto esperaban silenciosamente que no reconoci\u00e9ramos desde lejos. Beatriz no fue la primera en sufrir las consecuencias de la criminalizaci\u00f3n del aborto en El Salvador, al igual que <\/span><a href=\"https:\/\/fosfeminista.orgmedia\/justyna-wydrzynskas-case\/\"><span style=\"font-weight: 400;\">Justyna Wydrzy\u0144ska<\/span><\/a><span style=\"font-weight: 400;\"> no fue la primera en verse amenazada por las sanciones penales de Polonia. Y semana tras semana, vemos c\u00f3mo l\u00edderes extremistas de Estados Unidos presentan proyectos de ley para penalizar la atenci\u00f3n al aborto. Pero el movimiento feminista global es m\u00e1s fuerte que nunca y perseverar\u00e1 sin descanso. Por cada extremista antiaborto, hay una docena de feministas dispuestas y ansiosas por dedicar toda su energ\u00eda a proteger a las comunidades marginadas que se ven m\u00e1s afectadas por las draconianas leyes de penalizaci\u00f3n.<\/span>\n\n<span style=\"font-weight: 400;\">\u201cInstamos a la comunidad internacional a que se una a nosotros para apoyar el movimiento #JusticiaParaBeatriz y defender los derechos de las personas en El Salvador que buscan servicios de aborto. Ahora es el momento de dar un paso al frente y defender los derechos que est\u00e1n siendo atacados por los extremistas antiaborto. Mientras en Washington D. C. levantamos nuestros pa\u00f1uelos verdes en se\u00f1al de solidaridad y alzamos nuestras voces para luchar contra la crueldad y el extremismo antiaborto, prestamos la fuerza del movimiento feminista global a quienes lo necesitan y nos unimos a todos los aliados que defienden valientemente nuestras libertades\u201d.\u201d<\/span><\/blockquote>\n<em><span style=\"font-weight: 400;\">Antecedentes sobre <\/span><a href=\"https:\/\/justiciaparabeatriz.org\/en\/\"><span style=\"font-weight: 400;\"># Justicia para Beatriz<\/span><\/a><span style=\"font-weight: 400;\"> (<\/span><a href=\"https:\/\/justiciaparabeatriz.org\/en\/\"><span style=\"font-weight: 400;\"># Justicia para Beatriz<\/span><\/a><span style=\"font-weight: 400;\">):<\/span><\/em>\n\n<span style=\"font-weight: 400;\">\u201cBeatriz\u201d era el nombre de una joven y madre de una zona rural de El Salvador. Beatriz, que viv\u00eda en extrema pobreza y padec\u00eda lupus, luch\u00f3 contra el gobierno salvadore\u00f1o para interrumpir su embarazo, que pon\u00eda en riesgo su salud y en el que se diagnostic\u00f3 al feto malformaciones que le impedir\u00edan vivir fuera del \u00fatero. Beatriz finalmente pudo interrumpir su embarazo, pero su salud se vio gravemente afectada. Demand\u00f3 al gobierno, exigiendo una indemnizaci\u00f3n y que ninguna otra mujer tuviera que pasar por lo que ella se vio obligada a pasar. Aunque Beatriz falleci\u00f3 tristemente en 2017, su historia revel\u00f3 al mundo las graves consecuencias de la criminalizaci\u00f3n absoluta del aborto.<\/span>\n\n<span style=\"font-weight: 400;\">Los d\u00edas 22 y 23 de marzo de 2023, la Corte Interamericana de Derechos Humanos celebr\u00f3 una audiencia p\u00fablica presencial en Costa Rica en el caso de <\/span><i><span style=\"font-weight: 400;\">Beatriz contra El Salvador, <\/span><\/i><span style=\"font-weight: 400;\">marcando la primera vez que la Corte IACHR abord\u00f3 plenamente la cuesti\u00f3n del aborto. El caso de Beatriz pone de relieve la situaci\u00f3n a la que se enfrentan las mujeres en el sistema de salud p\u00fablica salvadore\u00f1o, donde el aborto est\u00e1 totalmente prohibido, incluso en circunstancias en las que su vida y su salud corren peligro, y demuestra la profunda injusticia de las leyes que no tienen en cuenta las condiciones y necesidades de las personas que quedan embarazadas.\u00a0<\/span>\n\n<span style=\"font-weight: 400;\">El Salvador y ahora Estados Unidos forman parte del reducido club de solo cuatro pa\u00edses que han revocado el derecho al aborto a su poblaci\u00f3n despu\u00e9s de haberlo concedido. Al igual que en El Salvador, ahora hay <\/span><a href=\"https:\/\/www.theguardian.com\/us-news\/2023\/mar\/10\/republican-wave-state-bills-homicide-charges\"><span style=\"font-weight: 400;\">un ritmo constante de esfuerzos leg\u00edtimos pero escandalosos<\/span><\/a><span style=\"font-weight: 400;\"> en los Estados Unidos para penalizar el aborto a las personas embarazadas y\/o a quienes las apoyan. El caso de Beatriz es solo un ejemplo de las muchas mujeres de todo el mundo que han muerto o han sido encarceladas por sufrir emergencias obst\u00e9tricas y otros problemas relacionados con el aborto.<\/span>\n\n<span style=\"font-weight: 400;\">Para m\u00e1s informaci\u00f3n, visite <a href=\"https:\/\/justiciaparabeatriz.org\">www.justiciaparabeatriz.org<\/a><\/span>\n\n<i><span style=\"font-weight: 400;\">####<\/span><\/i>\n\n<a href=\"https:\/\/fosfeminista.orgabout-us\/\"><i><span style=\"font-weight: 400;\">F\u00f2s Feminista<\/span><\/i><\/a><i><span style=\"font-weight: 400;\"> es una alianza feminista internacional centrada en la salud, los derechos y la justicia sexuales y reproductivos de las mujeres, las ni\u00f1as y las personas de g\u00e9nero diverso. Junto con m\u00e1s de 220 organizaciones de 40 pa\u00edses de todo el mundo, nos dedicamos a la atenci\u00f3n sanitaria, la educaci\u00f3n y la defensa de nuestros objetivos. Esto incluye la prestaci\u00f3n de servicios de salud sexual y reproductiva y la aplicaci\u00f3n de estrategias comunitarias que faciliten el acceso a la atenci\u00f3n sanitaria sexual y reproductiva a las mujeres, las ni\u00f1as y otras personas marginadas. Tambi\u00e9n involucramos a los j\u00f3venes con una educaci\u00f3n sexual integral y brindamos atenci\u00f3n a las sobrevivientes de la violencia de g\u00e9nero. Nos unimos a nuestros socios en las calles, en los tribunales y en otros espacios de defensa como una voz feminista sin complejos, resistiendo la injusticia y defendiendo la igualdad de g\u00e9nero y los derechos reproductivos a nivel local y mundial.<\/span><\/i>\n\n<b>Contacto: <\/b><a href=\"mailto:mboldt@mrss.com\"><b>mboldt@mrss.com<\/b><\/a><b>\u00a0<\/b>","":null,"anchor_id":""}}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00f2s Feminista Celebrates U.S. House Resolution in Support of #JusticeforBeatriz - F\u00f2s Feminista<\/title>\n<meta name=\"description\" content=\"F\u00f2s Feminista applauds U.S. Representative Nikema Williams\u2019 introduction of a House resolution that offers solidarity with feminists in El Salvador.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fosfeminista.org\/es\/news-and-stories\/resolution-justiceforbeatriz\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00f2s Feminista Celebrates U.S. House Resolution in Support of #JusticeforBeatriz - F\u00f2s Feminista\" \/>\n<meta property=\"og:description\" content=\"F\u00f2s Feminista applauds U.S. Representative Nikema Williams\u2019 introduction of a House resolution that offers solidarity with feminists in El Salvador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fosfeminista.org\/es\/news-and-stories\/resolution-justiceforbeatriz\/\" \/>\n<meta property=\"og:site_name\" content=\"F\u00f2s Feminista\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T22:07:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fosfeminista.org\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-09-a-las-8.41.18.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1580\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/resolution-justiceforbeatriz\\\/\",\"url\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/resolution-justiceforbeatriz\\\/\",\"name\":\"F\u00f2s Feminista Celebrates U.S. House Resolution in Support of #JusticeforBeatriz - F\u00f2s Feminista\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/resolution-justiceforbeatriz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/resolution-justiceforbeatriz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fosfeminista.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Captura-de-pantalla-2023-05-09-a-las-8.41.18.jpg\",\"datePublished\":\"2023-05-09T18:46:34+00:00\",\"dateModified\":\"2025-09-19T22:07:52+00:00\",\"description\":\"F\u00f2s Feminista applauds U.S. Representative Nikema Williams\u2019 introduction of a House resolution that offers solidarity with feminists in El Salvador.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/resolution-justiceforbeatriz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/resolution-justiceforbeatriz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/resolution-justiceforbeatriz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fosfeminista.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Captura-de-pantalla-2023-05-09-a-las-8.41.18.jpg\",\"contentUrl\":\"https:\\\/\\\/fosfeminista.org\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Captura-de-pantalla-2023-05-09-a-las-8.41.18.jpg\",\"width\":1580,\"height\":1182},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/news-and-stories\\\/resolution-justiceforbeatriz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fosfeminista.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00f2s Feminista Celebrates U.S. House Resolution in Support of #JusticeforBeatriz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fosfeminista.org\\\/#website\",\"url\":\"https:\\\/\\\/fosfeminista.org\\\/\",\"name\":\"F\u00f2s Feminista\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fosfeminista.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00f2s Feminista Celebrates U.S. House Resolution in Support of #JusticeforBeatriz - F\u00f2s Feminista","description":"F\u00f2s Feminista applauds U.S. Representative Nikema Williams\u2019 introduction of a House resolution that offers solidarity with feminists in El Salvador.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fosfeminista.org\/es\/news-and-stories\/resolution-justiceforbeatriz\/","og_locale":"es_MX","og_type":"article","og_title":"F\u00f2s Feminista Celebrates U.S. House Resolution in Support of #JusticeforBeatriz - F\u00f2s Feminista","og_description":"F\u00f2s Feminista applauds U.S. Representative Nikema Williams\u2019 introduction of a House resolution that offers solidarity with feminists in El Salvador.","og_url":"https:\/\/fosfeminista.org\/es\/news-and-stories\/resolution-justiceforbeatriz\/","og_site_name":"F\u00f2s Feminista","article_modified_time":"2025-09-19T22:07:52+00:00","og_image":[{"width":1580,"height":1182,"url":"https:\/\/fosfeminista.org\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-09-a-las-8.41.18.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fosfeminista.org\/news-and-stories\/resolution-justiceforbeatriz\/","url":"https:\/\/fosfeminista.org\/news-and-stories\/resolution-justiceforbeatriz\/","name":"F\u00f2s Feminista Celebrates U.S. House Resolution in Support of #JusticeforBeatriz - F\u00f2s Feminista","isPartOf":{"@id":"https:\/\/fosfeminista.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fosfeminista.org\/news-and-stories\/resolution-justiceforbeatriz\/#primaryimage"},"image":{"@id":"https:\/\/fosfeminista.org\/news-and-stories\/resolution-justiceforbeatriz\/#primaryimage"},"thumbnailUrl":"https:\/\/fosfeminista.org\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-09-a-las-8.41.18.jpg","datePublished":"2023-05-09T18:46:34+00:00","dateModified":"2025-09-19T22:07:52+00:00","description":"F\u00f2s Feminista applauds U.S. Representative Nikema Williams\u2019 introduction of a House resolution that offers solidarity with feminists in El Salvador.","breadcrumb":{"@id":"https:\/\/fosfeminista.org\/news-and-stories\/resolution-justiceforbeatriz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fosfeminista.org\/news-and-stories\/resolution-justiceforbeatriz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fosfeminista.org\/news-and-stories\/resolution-justiceforbeatriz\/#primaryimage","url":"https:\/\/fosfeminista.org\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-09-a-las-8.41.18.jpg","contentUrl":"https:\/\/fosfeminista.org\/wp-content\/uploads\/2023\/05\/Captura-de-pantalla-2023-05-09-a-las-8.41.18.jpg","width":1580,"height":1182},{"@type":"BreadcrumbList","@id":"https:\/\/fosfeminista.org\/news-and-stories\/resolution-justiceforbeatriz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fosfeminista.org\/"},{"@type":"ListItem","position":2,"name":"F\u00f2s Feminista Celebrates U.S. House Resolution in Support of #JusticeforBeatriz"}]},{"@type":"WebSite","@id":"https:\/\/fosfeminista.org\/#website","url":"https:\/\/fosfeminista.org\/","name":"F\u00f2s Feminista","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fosfeminista.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/fosfeminista.org\/es\/wp-json\/wp\/v2\/article\/4854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fosfeminista.org\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/fosfeminista.org\/es\/wp-json\/wp\/v2\/types\/article"}],"version-history":[{"count":1,"href":"https:\/\/fosfeminista.org\/es\/wp-json\/wp\/v2\/article\/4854\/revisions"}],"predecessor-version":[{"id":5091,"href":"https:\/\/fosfeminista.org\/es\/wp-json\/wp\/v2\/article\/4854\/revisions\/5091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fosfeminista.org\/es\/wp-json\/wp\/v2\/media\/3484"}],"wp:attachment":[{"href":"https:\/\/fosfeminista.org\/es\/wp-json\/wp\/v2\/media?parent=4854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}